

{"id":170,"count":5,"description":"","link":"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/","name":"Travel &amp; Tourism","slug":"travel-tourism","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Travel &amp; Tourism Archives - AAFT Online Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel &amp; Tourism Archives - AAFT Online Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/\" \/>\n<meta property=\"og:site_name\" content=\"AAFT Online Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/\",\"url\":\"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/\",\"name\":\"Travel &amp; Tourism Archives - AAFT Online Blog\",\"isPartOf\":{\"@id\":\"https:\/\/aaftonline.com\/blog\/home\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aaftonline.com\/blog\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel &amp; Tourism\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aaftonline.com\/blog\/home\/#website\",\"url\":\"https:\/\/aaftonline.com\/blog\/home\/\",\"name\":\"AAFT Online Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aaftonline.com\/blog\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel &amp; Tourism Archives - AAFT Online Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Travel &amp; Tourism Archives - AAFT Online Blog","og_url":"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/","og_site_name":"AAFT Online Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/","url":"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/","name":"Travel &amp; Tourism Archives - AAFT Online Blog","isPartOf":{"@id":"https:\/\/aaftonline.com\/blog\/home\/#website"},"breadcrumb":{"@id":"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/aaftonline.com\/blog\/home\/category\/travel-tourism\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aaftonline.com\/blog\/home\/"},{"@type":"ListItem","position":2,"name":"Travel &amp; Tourism"}]},{"@type":"WebSite","@id":"https:\/\/aaftonline.com\/blog\/home\/#website","url":"https:\/\/aaftonline.com\/blog\/home\/","name":"AAFT Online Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aaftonline.com\/blog\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/aaftonline.com\/blog\/home\/wp-json\/wp\/v2\/categories\/170"}],"collection":[{"href":"https:\/\/aaftonline.com\/blog\/home\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/aaftonline.com\/blog\/home\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/aaftonline.com\/blog\/home\/wp-json\/wp\/v2\/posts?categories=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}